{"id":239,"date":"2021-07-14T18:12:41","date_gmt":"2021-07-14T18:12:41","guid":{"rendered":"https:\/\/mushroomdosagecalculator.com\/2021\/07\/14\/shotgun-fruiting-machine-create-your-mushroom-growing-box-in-5-steps\/"},"modified":"2021-07-14T18:16:23","modified_gmt":"2021-07-14T18:16:23","slug":"shotgun-fruiting-machine-create-your-mushroom-growing-box-in-5-steps","status":"publish","type":"post","link":"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/","title":{"rendered":"Macchina per la fruttificazione a fucile: create la vostra cassetta per la coltivazione dei funghi in 5 passi"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment-large size-large lazy wp-post-image\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Camara-fructificadora.jpg\" alt=\"Camera di fruttificazione\" width=\"600\" height=\"330\" \/><\/p>\n<p>Adoro raccogliere i funghi. Purtroppo i funghi sono piuttosto esigenti. Pertanto, <strong>per ottenere buoni frutti \u00e8 necessario sottoporle a condizioni di crescita ideali<\/strong>. La costruzione di una fucina da frutto \u00e8 un modo semplice e veloce per ottenere il perfetto equilibrio di aria fresca e umidit\u00e0 di cui i funghi hanno bisogno. Sfoglia questo contenuto<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_74 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice dei contenuti<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a046ad66576f\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a046ad66576f\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#What_is_a_shotgun_fruiter\" >Che cos'\u00e8 un fucile da caccia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#What_is_perlite\" >Che cos'\u00e8 la perlite?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Preparation_before_building_the_chamber\" >Preparazione prima della costruzione della camera<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Necessary_materials\" >Materiali necessari<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Tools_needed\" >Strumenti necessari<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Steps_to_build_a_shotgun_fruiting_chamber_at_home\" >Come costruire una camera di fruttificazione per fucili da caccia a casa propria<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Step_1_mark_the_holes\" >Fase 1: segnare i fori<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Step_2_drill_the_holes\" >Fase 2: praticare i fori<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Step_3_fill_the_bottom_with_pearlite\" >Fase 3: riempire il fondo con perlite<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Step_4_soak_the_perlite\" >Fase 4: bagnare la perlite<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Step_5_place_the_mushroom_block_in_the_shotgun_fruiting_machine\" >Fase 5: collocare il blocco di funghi nella macchina per la fruttificazione a pallini<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#How_to_use_a_shotgun_fruiting_machine\" >Come usare una macchina per la fruttificazione a pallini<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Ventilation_and_spraying\" >Ventilazione e spruzzatura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Using_a_hygrometer\" >Utilizzo di un igrometro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#Lighting_the_fruiting_chamber\" >Illuminazione della camera di fruttificazione<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/mushroomdosagecalculator.com\/it\/macchina-per-la-fruttificazione-a-pallini-create-la-vostra-cassetta-per-la-coltivazione-dei-funghi-in-5-passi\/#A_quick_and_easy_solution\" >Una soluzione semplice e veloce<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"What_is_a_shotgun_fruiter\"><\/span>Che cos'\u00e8 un fucile da caccia?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La camera di fruttificazione di un fucile da caccia non \u00e8 altro che <strong>una scatola trasparente con fori<\/strong> e riempito con qualche centimetro di perlite umida sul fondo. I fori consentono lo scambio di aria fresca e gas. Mentre la perlite permette di mantenere l'umidit\u00e0. La scatola deve essere trasparente in modo che la giusta quantit\u00e0 di luce naturale la attraversi e raggiunga i funghi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-79 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Fructificadora-shotgun-sencilla.jpg\" alt=\"Macchina per la fruttificazione a pallini semplice\" width=\"600\" height=\"330\" \/>Un semplice fucile da caccia fruttifero. Il suo nome (\"shotgun\" in inglese) si riferisce alla disposizione dei fori nella scatola.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"What_is_perlite\"><\/span>Che cos'\u00e8 la perlite?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La perlite \u00e8 un minerale vulcanico presente in natura che, una volta espanso, forma un granulo ruvido e poroso con una superficie relativamente ampia. Le sporgenze e le fessure dei granuli di perlite <strong>sono in grado di immagazzinare acqua, che evapora con il tempo<\/strong>. Questa evaporazione consente di mantenere un'elevata umidit\u00e0 relativa all'interno della camera di fruttificazione.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-80 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Perlita-granulada.jpg\" alt=\"Perlite granulata\" width=\"600\" height=\"330\" \/>Un mucchietto di perlite granulare. Dovreste essere in grado di trovarla in un negozio di giardinaggio.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Preparation_before_building_the_chamber\"><\/span>Preparazione prima della costruzione della camera<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Costruire un fucile da caccia <strong>non ci vorr\u00e0 molto tempo e vi serviranno solo pochi strumenti.<\/strong> comunemente utilizzati. Una volta che avete tutti i materiali necessari, dovreste essere in grado di costruire la vostra camera di fruttificazione in meno di un'ora.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Necessary_materials\"><\/span>Materiali necessari<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Una scatola di plastica trasparente da 80 litri.<\/li>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> 12-14 litri di perlite granulare.<\/li>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Un flacone spray.<\/li>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Un igrometro (opzionale).<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"Tools_needed\"><\/span>Strumenti necessari<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Forare con una punta da 6 millimetri.<\/li>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Nastro di misurazione.<\/li>\n<li><i class=\"sui sui-check\" style=\"color: #9194c9;\"><\/i> Pennarello.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Steps_to_build_a_shotgun_fruiting_chamber_at_home\"><\/span>Come costruire una camera di fruttificazione per fucili da caccia a casa propria<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Andate avanti.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Step_1_mark_the_holes\"><\/span>Fase 1: segnare i fori<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Spaziatura dei fori Per ottenere un flusso d'aria adeguato attraverso il fucile da caccia, <strong>\u00e8 necessario praticare fori uniformemente distanziati su tutte e sei le facce della scatola.<\/strong>compresi la parte superiore e quella inferiore. In generale, i fori dovrebbero essere disposti a griglia a circa 5 centimetri di distanza l'uno dall'altro. Per realizzarli, segnateli prima con un pennarello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-81 size-full lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Persona-usando-cuadricula.jpg\" alt=\"Persona che utilizza la griglia\" width=\"600\" height=\"330\" \/>Segnare i fori formando una griglia con una distanza di 5 centimetri.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-82 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Tapa-de-plastico-agujeros.jpg\" alt=\"Fori del tappo in plastica\" width=\"600\" height=\"330\" \/>\u00c8 necessario praticare i fori su tutte e sei le facce, comprese quelle superiori e inferiori.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Step_2_drill_the_holes\"><\/span>Fase 2: praticare i fori<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Dimensioni Eseguire tutti i fori segnati <strong>utilizzando una punta da 6 millimetri<\/strong>. Assicuratevi di non stringere troppo, altrimenti la scatola si romper\u00e0 quando la forerete. \u00c8 inoltre necessario levigare i fori per assicurarsi che non vi siano schegge o residui di plastica intorno ai bordi. Si tratta di un'operazione ripetitiva, ma non dovrebbe richiedere molto tempo.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Persona-usando-talandro-tapa.jpg\" alt=\"Persona che indossa una cuffia a bretella\" width=\"600\" height=\"330\" \/>Utilizzare una punta da 6 millimetri per praticare tutti i fori. Ci vorr\u00e0 un po' di tempo!<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Step_3_fill_the_bottom_with_pearlite\"><\/span>Fase 3: riempire il fondo con perlite<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Riempire il fondo del fucile da caccia con circa 5 cm di perlite. La quantit\u00e0 esatta non ha molta importanza. Coprite uniformemente Assicuratevi solo di <strong>mettere una quantit\u00e0 sufficiente a coprire uniformemente il fondo<\/strong> fuori dalla scatola con qualche centimetro. Inoltre, dovete assicurarvi di usare perlite granulare. Se \u00e8 macinata troppo fine, molta di essa uscir\u00e0 dai fori praticati, facendo perdere tutto. Inoltre, <strong>La perlite fine non trattiene l'acqua come il granulato.<\/strong>.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-84 size-full lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Persona-perlita-humeda.jpg\" alt=\"Persona perlite bagnata\" width=\"600\" height=\"330\" \/>\u00c8 necessario bagnare la perlite fino a renderla molto umida.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Step_4_soak_the_perlite\"><\/span>Fase 4: bagnare la perlite<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Bagnare la perlite versando l'acqua nella macchina per la fruttificazione e mescolandola. <strong>finch\u00e9 la perlite non \u00e8 uniformemente inumidita<\/strong>. Non \u00e8 necessario versare l'acqua in modo che fuoriesca dal fondo della cassetta. L'intenzione \u00e8 di ricoprirla d'acqua in modo che possa evaporare nel tempo, aumentando l'umidit\u00e0 della camera di fruttificazione.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Step_5_place_the_mushroom_block_in_the_shotgun_fruiting_machine\"><\/span>Fase 5: collocare il blocco di funghi nella macchina per la fruttificazione a pallini<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ora avete un ambiente ragionevolmente umido, in grado di scambiare gas e ricevere aria fresca. Coltivate tutto. Pertanto, questa \u00e8 una macchina fotografica perfettamente <strong>valido per la coltivazione di tutti i tipi di funghi su piccola scala<\/strong>. L'uso tipico di un fruttificatore a pallini \u00e8 la coltivazione di funghi con la tecnica PF. Tuttavia, l'uso di blocchi fruttiferi di segatura o anche di kit per la coltivazione di funghi sar\u00e0 altrettanto facile. Anche se non \u00e8 del tutto necessario, <strong>un igrometro \u00e8 uno strumento utile<\/strong> che si pu\u00f2 collocare nella camera di fruttificazione per controllare i livelli di umidit\u00e0. Questo vi dar\u00e0 un'idea abbastanza precisa della necessit\u00e0 di spruzzare acqua all'interno della camera. Con il tempo, imparerete a conoscere i livelli di umidit\u00e0 pi\u00f9 adatti alle diverse fasi del ciclo di fruttificazione.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-85 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Bloque-de-hongos-camara.jpg\" alt=\"Blocco di funghi a camera\" width=\"600\" height=\"330\" \/>Un piccolo blocco di funghi in una camera di fruttificazione umida<\/p>\n<h2><span class=\"ez-toc-section\" id=\"How_to_use_a_shotgun_fruiting_machine\"><\/span>Come usare una macchina per la fruttificazione a pallini<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le camere di fruttificazione <strong>Quasi senza manutenzione<\/strong>Nonostante ci\u00f2, esistono una serie di buone pratiche da seguire per utilizzare un fruttificatore a pallini.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Ventilation_and_spraying\"><\/span>Ventilazione e spruzzatura<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>I fori situati sulle sei facce della camera fruttifera consentono l'introduzione di aria fresca e lo scambio di gas. Come ventilare? Tuttavia, questi fori non sono sufficienti da soli. Quando si inseriscono i blocchi di funghi nella macchina per la fruttificazione a pallini, <strong>Almeno due volte al giorno si dovrebbe togliere il coperchio e lasciarlo arieggiare.<\/strong>. Inoltre, per mantenere l'umidit\u00e0 dopo aver ventilato l'interno con aria secca, <strong>\u00e8 necessario inumidire la fotocamera<\/strong>. Per farlo, si pu\u00f2 utilizzare un tipico flacone spray con cui bagnare bene le pareti e il fondo di perlite con acqua. Cercate di farlo senza spruzzare direttamente il blocco fungino, poich\u00e9 le gocce d'acqua possono causare problemi al micelio o ai funghi, come ad esempio macchie causate da batteri.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-88 lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Botella-con-pulverizador.jpg\" alt=\"Bottiglia spray\" width=\"600\" height=\"330\" \/>Un semplice flacone spray per inumidire la camera<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Using_a_hygrometer\"><\/span>Utilizzo di un igrometro<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>L'igrometro \u00e8 uno strumento <strong>utile per il controllo dell'umidit\u00e0<\/strong> del vostro fucile da frutta. Anche se non \u00e8 assolutamente necessario, vi aiuter\u00e0 ad avere un'idea pi\u00f9 chiara se state ottenendo un ambiente con un livello di umidit\u00e0 adeguato.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-86 aligncenter lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/higrometro.jpg\" alt=\"igrometro\" width=\"450\" height=\"450\" \/><\/p>\n<p>Percentuale di umidit\u00e0 A seconda della fase del ciclo di fruttificazione del fungo, <strong>l'umidit\u00e0 deve essere compresa tra il 75 e il 90 per cento<\/strong>. Se l'umidit\u00e0 scende troppo, i vostri funghi avranno cappelli pi\u00f9 piccoli e screpolati, o potrebbero addirittura non arrivare a maturazione. Non importa se acquistate un igrometro digitale o analogico. Basta assicurarsi che il campo di misurazione del dispositivo consenta di misurare l'umidit\u00e0 relativa fino ad almeno 90%. In questo senso, \u00e8 necessario tenere presente che <strong>alcuni idrometri domestici non sono in grado di misurare con precisione umidit\u00e0 cos\u00ec elevate<\/strong>. Cercate i tipi di igrometri utilizzati negli umidificatori per sigari, in quanto sono in grado di misurare con precisione alti livelli di umidit\u00e0 relativa.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Lighting_the_fruiting_chamber\"><\/span>Illuminazione della camera di fruttificazione<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Contrariamente a quanto si crede, la maggior parte dei funghi ha bisogno di una quantit\u00e0 adeguata di luce per formarsi correttamente. Tuttavia, hanno bisogno di questa luce per un motivo diverso dalle piante. Luce solare indiretta Il posto migliore per posizionare il vostro fucile da caccia \u00e8 quello in cui si trova il <strong>che riceve luce solare indiretta per la maggior parte della giornata<\/strong>. Se la luce cade direttamente, danneggia la crescita. Surriscalda la camera di fruttificazione e pu\u00f2 causare il deterioramento dei funghi. Di gran lunga, <strong>La luce naturale indiretta \u00e8 la migliore<\/strong>. Ad esempio, potete posizionare il set di frutta vicino a una finestra, ma lontano dai raggi del sole. Se non avete la possibilit\u00e0 di fornire luce naturale alla vostra collezione di pallini, potete sempre fornire luce artificiale.<br \/>\n<strong>Una buona opzione potrebbe essere quella di utilizzare una piccola luce fluorescente con un timer.<\/strong> che consente cicli giornalieri di accensione per 12 ore e poi di spegnimento per lo stesso tempo. In questo modo si simula un ciclo di luce naturale. Se si opta per questa alternativa, assicurarsi che la fonte di luce sia sufficientemente lontana per non surriscaldare la fotocamera.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-89 aligncenter lazy\" src=\"https:\/\/mushroomdosagecalculator.com\/wp-content\/uploads\/2021\/07\/Camara-fructificadora.jpg\" alt=\"Camera di fruttificazione\" width=\"600\" height=\"330\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"A_quick_and_easy_solution\"><\/span>Una soluzione semplice e veloce<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Esiste una moltitudine di modi per costruire una camera di fruttificazione complessa, utilizzando umidificatori automatici, ventilatori potenti e molto spazio. Tuttavia, all'inizio non c'\u00e8 nulla di sbagliato nell'utilizzare una camera di fruttificazione a pallini. \u00c8 un'ottima soluzione per fornire le condizioni ideali di cui i funghi hanno bisogno per fruttificare correttamente. Idea per i principianti Questo fa s\u00ec che il set di fruttificazione a sparo <strong>un'ottima opzione per i principianti che desiderano imparare<\/strong>. Anche per i coltivatori esperti che desiderano una camera di fruttificazione facile e veloce per gli esperimenti.<\/p>\n<h4 class=\"entry-title\"><\/h4>","protected":false},"excerpt":{"rendered":"<p>Adoro raccogliere i funghi. Purtroppo, i funghi sono piuttosto esigenti. Perci\u00f2, per farli fruttare bene, bisogna sottoporli [...]<\/p>","protected":false},"author":1,"featured_media":240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"table_tags":[],"class_list":["post-239","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magic-mushrooms"],"_links":{"self":[{"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/posts\/239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/comments?post=239"}],"version-history":[{"count":2,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/posts\/239\/revisions"}],"predecessor-version":[{"id":1253,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/posts\/239\/revisions\/1253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/media\/240"}],"wp:attachment":[{"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/media?parent=239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/categories?post=239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/tags?post=239"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/mushroomdosagecalculator.com\/it\/wp-json\/wp\/v2\/table_tags?post=239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}